{"id":655,"date":"2011-06-30T18:27:51","date_gmt":"2011-06-30T18:27:51","guid":{"rendered":"http:\/\/edublog.me\/spieleseminar\/?p=655"},"modified":"2011-07-02T05:11:30","modified_gmt":"2011-07-02T05:11:30","slug":"gratis-spiele-die-hangen-blieeiben","status":"publish","type":"post","link":"https:\/\/edublog.me\/spieleseminar\/2011\/06\/30\/gratis-spiele-die-hangen-blieeiben\/","title":{"rendered":"Gratis-Spiele, die h\u00e4ngen bl(ie\/ei)ben"},"content":{"rendered":"<p>Meine kleine Liste willk\u00fcrlich zusammen gestellter, frei erh\u00e4ltlicher (Computer)Spiele&#8230;<!--more--><\/p>\n<p><strong>Beste Parodie auf bekannte Spielprinzipien<\/strong><\/p>\n<p>Upgrade Complete &#8211; hier l\u00e4sst sich <em>wirklich alles<\/em> mit entsprechendem &#8220;Geld&#8221; upgraden. Eine Parodie auf das klassische behavioristische Spieldesign?<br \/>\n<a href=\"http:\/\/www.kongregate.com\/games\/ArmorGames\/upgrade-complete\">http:\/\/www.kongregate.com\/games\/ArmorGames\/upgrade-complete<\/a><\/p>\n<p>Super PSTW Action RPG &#8211; PSTW steht f\u00fcr &#8220;Press Space to Win&#8221;<br \/>\n<a href=\"http:\/\/www.newgrounds.com\/portal\/view\/495903\">http:\/\/www.newgrounds.com\/portal\/view\/495903<\/a><\/p>\n<p>Die visuell aufbereitete, gesprochene Rezension von Axman13 zu diesem Spiel h\u00e4tte es fast in die n\u00e4chste Kategorie geschafft:<\/p>\n<p>[youtube]http:\/\/www.youtube.com\/watch?v=4Z2Z23SAFVA[\/youtube]<a href=\"http:\/\/www.youtube.com\/watch?v=4Z2Z23SAFVA\">http:\/\/www.youtube.com\/watch?v=4Z2Z23SAFVA<\/a><\/p>\n<p><strong>Traurigste transmediale Darstellung eines Spiels<\/strong><\/p>\n<p>L\u00e4sst sich der Inhalt eines Mediums (Spiel) durch ein anderes darstellen?<br \/>\nWas geht verloren, was wird gewonnen?<\/p>\n<p>Trailer for upcoming zombie game: Dead Island<br \/>\n<a href=\"http:\/\/www.boingboing.net\/2011\/02\/17\/trailer-for-upcoming.html\">http:\/\/www.boingboing.net\/2011\/02\/17\/trailer-for-upcoming.html<\/a><\/p>\n<p>Every Day the Same Dream<br \/>\n<a href=\"http:\/\/www.boingboing.net\/2010\/06\/03\/video-molleindustria.html\">http:\/\/www.boingboing.net\/2010\/06\/03\/video-molleindustria.html<\/a><\/p>\n<p><strong>Unerwartetste klassisch-didaktische Lernerfahrung<\/strong><\/p>\n<p>Fake for Real &#8211; Es steckt Baudrillard&#8217;sches Potenzial im Klassiker &#8220;Memory&#8221;<br \/>\n<a href=\"http:\/\/www.fakeforreal.com\/\">http:\/\/www.fakeforreal.com\/<\/a><\/p>\n<p>Big Al &#8211; das Leben eines Allosaurusjungen<br \/>\n<a href=\"http:\/\/www.bbc.co.uk\/sn\/prehistoric_life\/games\/big_al\/\">http:\/\/www.bbc.co.uk\/sn\/prehistoric_life\/games\/big_al\/<\/a><\/p>\n<p>Light Bot &#8211; Programmieren Lernen<br \/>\n<a href=\"http:\/\/armorgames.com\/play\/2205\/light-bot\">http:\/\/armorgames.com\/play\/2205\/light-bot<\/a><\/p>\n<p>Add&#8217;em up &#8211; Addieren und Subtrahieren \u00fcben<br \/>\n<a href=\"http:\/\/www.addictinggames.com\/puzzle-games\/addemup.jsp\">http:\/\/www.addictinggames.com\/puzzle-games\/addemup.jsp<\/a><\/p>\n<p>Pandemic 2 &#8211; Eine Krankheit spielen&#8230;<br \/>\n<a href=\"http:\/\/www.addictinggames.com\/pandemic2.html\">http:\/\/www.addictinggames.com\/pandemic2.html<\/a><\/p>\n<p>Bridgebuilder &#8211; Statik kann Spa\u00df machen&#8230;<br \/>\n<a href=\"http:\/\/www.google.de\/#sclient=psy&amp;hl=de&amp;safe=off&amp;source=hp&amp;q=bridgebuilder+download&amp;aq=f&amp;aqi=g-s1&amp;aql=&amp;oq=&amp;pbx=1&amp;bav=on.2,or.r_gc.r_pw.&amp;fp=2dc6757f5b631129&amp;biw=1145&amp;bih=593\">Google-Suchlink<\/a><\/p>\n<p><strong>Die gemeinsten behavioristisch funktionierenden Zeitfresser<\/strong><\/p>\n<p>Monster&#8217;s Den &#8211; Und es geht weiter, weiter, weiter&#8230;<br \/>\n<a href=\"http:\/\/www.addictinggames.com\/strategy-games\/monstersden.jsp\">http:\/\/www.addictinggames.com\/strategy-games\/monstersden.jsp<\/a><\/p>\n<p>Vector Tower Defense &#8211; hypnotisch!<br \/>\n<a href=\"http:\/\/www.candystand.com\/play\/vector-td\">http:\/\/www.candystand.com\/play\/vector-td<\/a><\/p>\n<p>Cursed Treasure &#8211; (Tower Defense) Sammeln und Aufsteigen<br \/>\n<a href=\"http:\/\/www.addictinggames.com\/cursed-treasure-game.html\">http:\/\/www.addictinggames.com\/cursed-treasure-game.html<\/a><\/p>\n<p>Extrapreis: Der vermutlich erfolgloseste Versuch, dieses Prinzip auf etwas Sinnvolles anzuwenden: Chore Wars &#8211; Claim Experience Points for Housework<br \/>\n<a href=\"http:\/\/www.chorewars.com\/index.php\">http:\/\/www.chorewars.com\/index.php<\/a><\/p>\n<p><strong>Das interessanteste Potenzial f\u00fcr Stealth-Teaching<\/strong><\/p>\n<p>The Last Stand &#8211; Geographie, Routenplanung, Haushaltsf\u00fchrung<br \/>\n<a href=\"http:\/\/armorgames.com\/play\/1443\/the-last-stand-2\">http:\/\/armorgames.com\/play\/1443\/the-last-stand-2<\/a><\/p>\n<p>Warfare 1917 &#8211; Die Schrecken des ersten Weltkriegs und die Sinnlosigkeit des Sterbens auf dem Schlachtfeld<br \/>\n<a href=\"http:\/\/armorgames.com\/play\/2267\/warfare-1917\">http:\/\/armorgames.com\/play\/2267\/warfare-1917<\/a><\/p>\n<p>Mytheria &#8211; Systemisches Denken<br \/>\n<a href=\"http:\/\/www.kongregate.com\/games\/DiffusionGames\/mytheria\">http:\/\/www.kongregate.com\/games\/DiffusionGames\/mytheria<\/a><\/p>\n<p><strong>Die interessantesten Spielideen<\/strong><\/p>\n<p>Steambirds &#8211; Rundenbasiertes Taktikspiel<br \/>\n<a href=\"http:\/\/armorgames.com\/play\/5426\/steambirds\">http:\/\/armorgames.com\/play\/5426\/steambirds<\/a><\/p>\n<p>99 Bricks &#8211; Interessantes Mashup aus Jenga und Tetris<br \/>\n<a href=\"http:\/\/www.kongregate.com\/games\/WeirdBeardGames\/99-bricks\">http:\/\/www.kongregate.com\/games\/WeirdBeardGames\/99-bricks<\/a><\/p>\n<p>Die Anstalt &#8211; Psychiatrie f\u00fcr misshandelte Kuscheltiere (ist zwar &#8216;Werbung&#8217;, aber angenehm &#8220;disturbing&#8221;)<br \/>\n<a href=\"http:\/\/www.parapluesch.de\/\">http:\/\/www.parapluesch.de\/<\/a><\/p>\n<p>Chronotron &#8211; Wenn du viele w\u00e4rst&#8230;<br \/>\n<a href=\"http:\/\/armorgames.com\/play\/1567\/chronotron\">http:\/\/armorgames.com\/play\/1567\/chronotron<\/a><\/p>\n<p>Shift &#8211; Konstruktivismusmetapher in S\/W<br \/>\n<a href=\"http:\/\/www.addictinggames.com\/shift3.html\">http:\/\/www.addictinggames.com\/shift3.html<\/a><\/p>\n<p>Orisinal Games &#8211; Microart, kein Spiel l\u00e4nger als eine Minute; kleine Spielideen, einfache bzw. bekannte Spielmechanismen, \u00e4sthetische Umsetzung<br \/>\n<a href=\"http:\/\/www.ferryhalim.com\/orisinal\/\">http:\/\/www.ferryhalim.com\/orisinal\/<\/a><\/p>\n<p><strong>Game Reviews<br \/>\n<\/strong><\/p>\n<p>Ayiti: the Cost of Life walkthrough, review, discussion, hints and tips &#8230;<br \/>\n<a href=\"http:\/\/jayisgames.com\/archives\/2006\/11\/cost_of_life.php\">http:\/\/jayisgames.com\/archives\/2006\/11\/cost_of_life.php<\/a><\/p>\n<p>Colossal Cave &#8211; Wir sprachen dar\u00fcber: Das Textadventure &#8220;Zork&#8221; und seine Vorl\u00e4ufer<br \/>\n<a href=\"http:\/\/www.rockpapershotgun.com\/2011\/06\/04\/colossal-cave-review\/\">http:\/\/www.rockpapershotgun.com\/2011\/06\/04\/colossal-cave-review\/<\/a><\/p>\n<p>Monopoly Killer: Perfect German Board Game Redefines Genre<br \/>\n<a href=\"http:\/\/www.wired.com\/gaming\/gamingreviews\/magazine\/17-04\/mf_settlers?currentPage=all\">http:\/\/www.wired.com\/gaming\/gamingreviews\/magazine\/17-04\/mf_settlers?currentPage=all<\/a><\/p>\n<p><strong>Diverser Pofel<\/strong><\/p>\n<p><strong><\/strong>Eines der \u00e4ltesten, weitverbreitetsten Spielgenres, mit sehr unterschiedlichen kulturellen Kontextualisierungen<br \/>\n<a href=\"http:\/\/en.wikipedia.org\/wiki\/Cross_and_circle_game\">http:\/\/en.wikipedia.org\/wiki\/Cross_and_circle_game<\/a><\/p>\n<p>Scoyo &#8211; Bertelsmanns gescheiterter Versuch, die Inhalte verbindlicher Lehrpl\u00e4ne in tausenden von Spielen abzubilden<a href=\"http:\/\/www-de.scoyo.com\/ausprobieren.html\"><br \/>\nhttp:\/\/www-de.scoyo.com\/ausprobieren.html<\/a><\/p>\n<p>How to Adapt Milton Bradley\u2019s \u201cTwister\u201d Game for blind people<br \/>\n<a href=\"http:\/\/www.nfb.org\/images\/nfb\/Publications\/fr\/fr27\/4\/fr270417.htm\">http:\/\/www.nfb.org\/images\/nfb\/Publications\/fr\/fr27\/4\/fr270417.htm<\/a><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"rTmbfNnQRH\"><p><a href=\"https:\/\/boingboing.net\/2010\/12\/16\/greenpeace-v-big-oil.html\">Greenpeace v Big Oil, the CC-released environmental game<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Greenpeace v Big Oil, the CC-released environmental game&#8221; &#8212; Boing Boing\" src=\"https:\/\/boingboing.net\/2010\/12\/16\/greenpeace-v-big-oil.html\/embed#?secret=EFNsjlZRiL#?secret=rTmbfNnQRH\" data-secret=\"rTmbfNnQRH\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"d5KG56ttn9\"><p><a href=\"https:\/\/boingboing.net\/2009\/11\/22\/augmented-reality-ri.html\">Augmented reality rig that turns you into a character in a third-person game<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Augmented reality rig that turns you into a character in a third-person game&#8221; &#8212; Boing Boing\" src=\"https:\/\/boingboing.net\/2009\/11\/22\/augmented-reality-ri.html\/embed#?secret=wES7X5xkzH#?secret=d5KG56ttn9\" data-secret=\"d5KG56ttn9\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Human Vs Zombie Survival MMORPG Game<br \/>\nhttp:\/\/www.brainchef.com\/securom\/zombie.game<\/p>\n<p>idleworm: gulf war game<br \/>\nhttp:\/\/www.idleworm.com\/nws\/2002\/11\/iraq2.shtml<\/p>\n<p><a href=\"http:\/\/armorgames.com\/play\/1376\/punk-o-matic\">http:\/\/armorgames.com\/play\/1376\/punk-o-matic<\/a><br \/>\nhttp:\/\/armorgames.com\/play\/7237\/punk-o-matic-2<\/p>\n<p>http:\/\/jacksonpollock.org\/<\/p>\n<p>http:\/\/armorgames.com\/play\/1623\/music-catch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meine kleine Liste willk\u00fcrlich zusammen gestellter, frei erh\u00e4ltlicher (Computer)Spiele&#8230;<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,20],"tags":[],"class_list":["post-655","post","type-post","status-publish","format-standard","hentry","category-spielbeispiele","category-wey"],"_links":{"self":[{"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/posts\/655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/comments?post=655"}],"version-history":[{"count":6,"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/posts\/655\/revisions"}],"predecessor-version":[{"id":692,"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/posts\/655\/revisions\/692"}],"wp:attachment":[{"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/media?parent=655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/categories?post=655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edublog.me\/spieleseminar\/wp-json\/wp\/v2\/tags?post=655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}